{"id":6562,"date":"2025-05-14T10:36:15","date_gmt":"2025-05-14T08:36:15","guid":{"rendered":"https:\/\/eba.hmy.temporary.site\/prodotto\/tappeto-pets-revolution-2\/"},"modified":"2026-05-13T14:03:17","modified_gmt":"2026-05-13T12:03:17","slug":"animaux-de-compagnie-revolution-2-carpet","status":"publish","type":"product","link":"https:\/\/unitedpets.com\/fr\/prodotto\/tappeto-pets-revolution-2\/","title":{"rendered":"Seletti - Rug PETS (R)EVOLUTION"},"content":{"rendered":"<h3>Seletti - Rug PETS (R)EVOLUTION<\/h3>\n<p>Seletti &#8211; Tappeto PETS (R)EVOLUTION. La gamma si arricchisce di nuovi elementi di design dedicato ai nostri amici a quattro zampe. La nuova collaborazione tra Seletti e United Pets da vita ad una linea di cucce per cani e gatti, quindi cuscini con stampa persiana in 2 misure, due colori e con fondo antiscivolo, un comodo e caldo per i nostri amici pelosi.<\/p>","protected":false},"excerpt":{"rendered":"<p data-start=\"43\" data-end=\"370\"><a href=\"https:\/\/unitedpets.com\/fr\/product-2\/animaux-de-compagnie-revolution-2-carpet\/\">Il tappeto PETS (R)EVOLUTION<\/a> di Seletti nasce dalla collaborazione con United Pets, portando design, comfort e funzionalit\u00e0 direttamente negli spazi dedicati ai nostri amici a quattro zampe. Pensato per offrire un\u2019area accogliente e calda, questo tappeto \u00e8 ideale per cani e gatti che amano rilassarsi in totale comodit\u00e0.<\/p>\n<p data-start=\"372\" data-end=\"770\">La collezione si arricchisce di nuovi elementi di design, tra cui cucce, cuscini con stampa persiana disponibili in due misure e due colori, tutti dotati di fondo antiscivolo per garantire stabilit\u00e0 e sicurezza durante l\u2019uso. Il tappeto, morbido e resistente, rappresenta una soluzione pratica per proteggere pavimenti e creare un\u2019area dedicata al riposo del tuo pet, senza rinunciare allo stile.<\/p>\n<p data-start=\"772\" data-end=\"913\" data-is-last-node=\"\" data-is-only-node=\"\">Un accessorio perfetto per chi desidera unire funzionalit\u00e0, comfort e un tocco di design innovativo nella vita quotidiana dei propri animali.<\/p>","protected":false},"featured_media":9155,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[55,63,64],"product_tag":[96],"discount-clusters":[],"collezioni":[333],"eco-friendly":[],"animal-type":[272],"designer":[275,306],"stagionalita":[115],"class_list":{"0":"post-6562","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cane","7":"product_cat-casa","8":"product_cat-cucce-e-cuscini","9":"product_tag-collab","10":"collezioni-ld","11":"animal-type-cane","12":"designer-seletti","13":"designer-united-pets","14":"stagionalita-pets-revolution","16":"first","17":"outofstock","18":"shipping-taxable","19":"purchasable","20":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/unitedpets.com\/fr\/wp-json\/wp\/v2\/product\/6562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unitedpets.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/unitedpets.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/unitedpets.com\/fr\/wp-json\/wp\/v2\/comments?post=6562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unitedpets.com\/fr\/wp-json\/wp\/v2\/media\/9155"}],"wp:attachment":[{"href":"https:\/\/unitedpets.com\/fr\/wp-json\/wp\/v2\/media?parent=6562"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/unitedpets.com\/fr\/wp-json\/wp\/v2\/product_brand?post=6562"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/unitedpets.com\/fr\/wp-json\/wp\/v2\/product_cat?post=6562"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/unitedpets.com\/fr\/wp-json\/wp\/v2\/product_tag?post=6562"},{"taxonomy":"discount-clusters","embeddable":true,"href":"https:\/\/unitedpets.com\/fr\/wp-json\/wp\/v2\/discount-clusters?post=6562"},{"taxonomy":"collezioni","embeddable":true,"href":"https:\/\/unitedpets.com\/fr\/wp-json\/wp\/v2\/collezioni?post=6562"},{"taxonomy":"eco-friendly","embeddable":true,"href":"https:\/\/unitedpets.com\/fr\/wp-json\/wp\/v2\/eco-friendly?post=6562"},{"taxonomy":"animal-type","embeddable":true,"href":"https:\/\/unitedpets.com\/fr\/wp-json\/wp\/v2\/animal-type?post=6562"},{"taxonomy":"designer","embeddable":true,"href":"https:\/\/unitedpets.com\/fr\/wp-json\/wp\/v2\/designer?post=6562"},{"taxonomy":"stagionalita","embeddable":true,"href":"https:\/\/unitedpets.com\/fr\/wp-json\/wp\/v2\/stagionalita?post=6562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}